{"id":2945,"date":"2017-11-28T11:48:53","date_gmt":"2017-11-28T10:48:53","guid":{"rendered":"https:\/\/multidimensionalmusic.com\/?page_id=2945"},"modified":"2020-01-16T15:12:12","modified_gmt":"2020-01-16T14:12:12","slug":"eine-revolution-gesund-werden-durch-tone","status":"publish","type":"page","link":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/","title":{"rendered":"Eine Revolution, gesund werden durch T\u00f6ne"},"content":{"rendered":"<style type=\"text\/css\">body.kc-css-system .kc-css-3907141{margin-top: 20px;margin-bottom: 20px;padding-top: 10px;padding-bottom: 10px;}<\/style>\n<section class=\"kc-elm kc-css-3907141 kc_row\">\n<div class=\"kc-row-container  kc-container\">\n<div class=\"kc-wrap-columns\">\n<div class=\"kc-elm kc-css-3250809 kc_col-sm-12 kc_column col-md-12\">\n<div class=\"kc-col-container\">\n<div class=\"kc-elm kc-css-1410568 kc_text_block\">\n<h3 style=\"text-align: center;\"><strong>Press artikel<\/strong><\/h3>\n<h5>EINE MUSIK, DIE IHRE SCHWINGUNGEN Z\u00c4HMT, HARMONISIERT, IHRE ZELLEN REGENERIERT, GESUNDEN WIRD ZU EINER REALIT\u00c4T.<\/h5>\n<p>Eine erstaunliche Frau, mit ausdrucksstarkem Gesicht, mit Kopf und Herz dabei, dem Gegen\u00fcber zuzuh\u00f6ren:<br \/>Jacotte Chollet. Regisseurin von Fernsehreportagen.<br \/>Jahrelang hat sie den Planeten an der Seite ihres Ehemann`s Andre Voisin durchquert, um anderen die spirituellen Traditionen der ganzen Welt zu er\u00f6ffnen.<\/p>\n<p>Ganz pl\u00f6tzlich habe ich gesp\u00fcrt, dass ich etwas anderes tun muss, sagt sie, dass es auch f\u00fcr mich Zeit war, auf die andere Seite des Spiegels zu treten. Von der Betrachterin, der Zeugin, der Erz\u00e4hlerin war es n\u00f6tig, in die Rolle der Wegbereiterin zu treten.<br \/>Nach 7 Jahren innerer Suche, mit Hilfe von Klang-Synthesizern wird die &#8220;Multidimensionale Musik&#8221; (MMD) geschaffen.<br \/>Sie ist klangvolles Zeugnis, erkl\u00e4rt Jacotte Chollet, einer systematischen Untersuchung unbekannter R\u00e4ume unseres tiefsten Seins.<\/p>\n<p>Als sie ihre musikalischen Kreationen erneut h\u00f6rte, war sie sich dar\u00fcber im klaren, dass sie sich augenblicklich in einem erweiterten Bewusstseinszustand befand.<br \/>Dies erkl\u00e4rt sich in der Tat durch ein Ph\u00e4nomen der Resonanz und der Physikern wohlbekannten Harmonisierung, pr\u00e4zisiert sie.<br \/>Die Physiker haben schon lange beobachtet, dass, wenn eine Stimmgabel in einer bestimmten Tonlage schwingt , eine andere, die sich zwar in Ruhe, jedoch in der N\u00e4he befindet, in der gleichen Tonlage zu schwingen beginnt.<br \/>Das Gehirn arbeitet gleichfalls nach diesem System von Wellen, die durch das Gleiche hervorgerufen worden sind.<br \/>Auch die Personen, die Jacotte Chollet ihre Musik h\u00f6ren l\u00e4sst, kommen ebenfalls in einen ver\u00e4nderten Zustand des Bewusstseins und treten in einen Kontakt mit ihrem lichten Sein.<br \/>Sie erhalten dort sie selbst betreffende Informationen, in Form von Intuitionen, Bildern, und solche, die in Zusammenhang stehen mit psychischen Schwierigkeiten oder k\u00f6rperliche Empfindungen betreffen.<\/p>\n<p>Die Ebene von erweitertem Bewusstsein, auf die ich mich bringe, um die T\u00f6ne meiner Musik zu sch\u00f6pfen, ist ganz einfach die ber\u00fchmte superlichte Ebene, f\u00fcgt sie hinzu, die wir Professor Regis Dutheil zu verdanken haben.<br \/>Eine Ebene des Seins, in der weder Zeit noch Raum existieren, in der jede Information sich f\u00fcr das Bewusstsein zur Verf\u00fcgung bereit h\u00e4lt, wenn man auch nur etwas f\u00e4hig ist, sie zu empfangen.<br \/>Jeder aber ist dazu f\u00e4hig.<br \/>Die Channeler, die Medien, die Astralreisenden erreichen leicht dieses Niveau.<br \/>Aus diesem Grund hat Jacotte Chollet ihrer Musik den Namen Multidimensionalmusik gegeben.<\/p>\n<h5>DIE SUPERLICHTE MEDIZIN<\/h5>\n<p>Professor Regis Dutheil ist Physiker und Arzt. Er ist Autor eines weltweit bekannten Werkes, Die superlichte Medizin ( \u00e9ditions Sand ).<br \/>Er interessiert sich f\u00fcr Jacotte Chollet`s Arbeit und macht ihr grossen Mut.<\/p>\n<p>Er schreibt: Die multidimensionale Musik ist eine komplett neu geschaffene Methode. Sie besteht darin, unterschiedliche Zust\u00e4nde von Bewusstsein hervorzubringen und sie hat gleichzeitig eine heilende Wirkung: das Bewusstsein des Individuums beginnt, Botschaften zu den Schattenzonen oder zu den k\u00f6rperlichen Ebenen von Fehlfunktionen zu senden.<br \/>Diese Prinzip ist von Jacotte Chollet, die ihre Erfahrungen in der N\u00e4he von Chantilly in einem richtigen Labor verifiziert, entdeckt und zur Anwendung gebracht worden.<br \/>Ich m\u00f6chte an dieser Stelle unterstreichen, es handelt sich hierbei nicht um Musiktherapie, deren Ziel darin besteht, durch das H\u00f6ren klassischer Musikst\u00fccke bestimmte k\u00f6rperliche und mentale Krankheiten zu behandeln,wobei diese Musikst\u00fccke nach der Art der Erkrankung untersucht und ausgew\u00e4hlt werden.<br \/>Erwachen zu einer anderen Dimension.<br \/>Als sie sp\u00fcrt, dass sie bereit ist, in diesen erweiterten Zustand des Bewusstseins einzutreten , in dem sie ihre Inspiration verst\u00e4rken kann, schaltet sie das siebenspurige Tonbandger\u00e4t ihres Tonstudios an.<\/p>\n<p>Sie dringt in eine Art Sekund\u00e4rzustand ein, einen Zustand von Meditation, in dem ihr ihre Musik, die keiner anderen vergleichbar ist , quasi diktiert wird.<br \/>in diesem inneren Zustand, sagt sie, ist alles m\u00f6glich, es gibt weder Trennung noch Begrenzung noch Einschr\u00e4nkung sondern ganz im Gegensatz ein tiefes Gef\u00fchl von Einheit, von Zusammenhang und von Freude, das Schaffen geschieht von selbst, in einem Moment der sich ausdehnt bis ins Unendliche und wo Vergangenheit, Gegenwart und Zukunft miteinander verschmelzen.<br \/>Wie viele Komponisten h\u00f6rt Jacotte Cholet eine Musik, die sie schlie\u00dflich lediglich aufschreibt.<br \/>Die Noten, die ich h\u00f6re, sind meinen H\u00e4nden immer drei oder vier Takte voraus, sagt sie.<br \/>Ich bin nur ein Kanal zwischen den Botschaften dieser h\u00f6heren Bewusstseinsebenen und der irdischen Realit\u00e4t.<\/p>\n<p>Die schwingenden Klangfrequenzen scheinen eine Information zu \u00fcberbringen, die den ver\u00e4nderten Geweben eines Kranken erlaubt, mit anderen, gesunden Zellen des K\u00f6rpers zu in Gleichklang zu kommen.<br \/>Man k\u00f6nnte sogar sagen, dass die Zellen des Patienten sich in einem gewissen Sinne in Richtung einer generellen Harmonisierung orientieren, ist einmal das Signal dazu gegeben.<br \/>Mehr noch, dieses Aufsp\u00fcren von K\u00f6rperzonen, die von einer Krankheit betroffen sind, l\u00e4sst k\u00f6rperliche Signale entstehen, die an gewisse fr\u00fchere Erkrankungen oder Erfahrungen der Vergangenheit erinnert.<br \/>Dies war bei Pascale, 36 Jahre alt, der Fall. Sie litt an Missstimmungen, die unerkl\u00e4rlich blieben.<\/p>\n<p>Ich habe diese Musik geh\u00f6rt, diese Kl\u00e4nge, die, das habe ich erst sp\u00e4ter gewusst, genau auf meinen Zustand abgestimmt waren, und ich habe zun\u00e4chst ein tiefes Unbehagen gesp\u00fcrt, das in mir ein gewisses Bewusstsein geschaffen hat, um die Gr\u00fcnde dieses Unwohlseins zu analysieren. Ich habe entdeckt, dass ich nach einem viele Jahre zur\u00fcckliegenden chirurgischen Eingriff, die Phasen meiner Narkose und die mit meiner damaligen Krankheit zusammenh\u00e4ngenden Schmerzen wiedererlebt hatte und dass ich mein Unwohlsein auf unbewusster Ebene seit Jahren wiedererlebte. Von da an war mein Problem schnell gel\u00f6st.&#8221;<\/p>\n<h5>GESUNDEN WIRD ZUR REALIT\u00c4T<\/h5>\n<p>Lucien, der seit Jahren an einem Magengeschw\u00fcr leidet, hat ebenso starke Vibrationen gesp\u00fcrt, und so etwas wie eine Last in H\u00f6he des Solarplexus beim H\u00f6ren der einen oder der anderen Passage.<br \/>Indem er sich dank dieser Musik der Kr\u00e4fte bewusst geworden ist, die seinen energetischen K\u00f6rper beleben, konnte er durch Empfindungen die Knotenpunkte, wo diese Energie gehemmt war herausfinden.<br \/>Knoten, die sich in seinem K\u00f6rper in eine Krankheit und Leiden \u00fcbersetzt haben.<br \/>Zus\u00e4tzlich, auf diesem Niveau von h\u00f6herem Bewusstsein angelangt, konnte er ebenso die gewohnte Barriere von Unbewusstheit \u00fcberwinden und Bilder, Erinnerungen an sein pers\u00f6nliches Problem sind wieder in ihm wach geworden.<\/p>\n<p>Dieses Bewusstwerden, Psychologen und Psychoanalytiker wissen dies sehr wohl, entspricht immer dem Beginn der Heilung.<br \/>Lucien konnte die Dinge nun wieder neu aufrollen und, indem er den emotionalen Knoten l\u00f6ste, das Fliessen der Energien wieder herstellen.<\/p>\n<p>Ganz offensichtlich wird eine Heilung dieser Art von l\u00e4ngerer Dauer sein als eine medikament\u00f6se Behandlung, die immer nur auf die Folgen einer St\u00f6rung wirkt.<br \/>Um ein Bild zu benutzen, k\u00f6nnte man sagen, statt die M\u00e4ngel einer Photographie auf dem Papier, (K\u00f6rper) zu beheben, behebt man diese M\u00e4ngel direkt auf dem Negativ dieses Photos, (energetischer K\u00f6rper).<\/p>\n<p>Im ersteren Fall, wenn man einen Abzug macht (eine neue Krisenperiode im Leben) wird der Fehler, der latent immer noch existierte, auf dem Photo wieder erscheinen, im zweiten Fall, wird er nicht mehr erscheinen, da das Negativ einwandfrei war.<\/p>\n<p>Selbstverst\u00e4ndlich bringt das, was St\u00f6rungen behebt, die sich bereits auf physischer Ebene manifestiert haben, auch spektakul\u00e4re Ergebnisse im mentalen und psychologischen Bereich.<br \/>Der Fall von Adeline ist beispielhaft.<\/p>\n<p>Ich habe ein Leben ertragen, das nur eine lange Reihe von Misserfolgen war, beruflichen wie gef\u00fchlsm\u00e4\u00dfigen. Als ich bei Madame Chollet gelandet bin, war ich am Ende meiner Kraft und v\u00f6llig deprimiert.<br \/>Sofort, anl\u00e4sslich meines ersten H\u00f6rens, hatte ich ein spontanes zweites Gesicht, das hei\u00dft, ich habe nachweisbare und \u00fcberpr\u00fcfbare Informationen \u00fcber meine verstorbene Gro\u00dfmutter empfangen, und das hat mich Vertrauen fassen lassen.<br \/>Ich habe regelm\u00e4\u00dfig meine MMD-Sitzungen gemacht, und nach und nach konnte ich meine krankhafte Sch\u00fcchternheit, meine Mimosenhaftigkeit besiegen, die mich daran hinderten, anderen gegen\u00fcber meine tiefen Gef\u00fchle zu verraten, genauso wie meine Meinung, meine \u00dcberzeugungen, meine Sichtweisen oder meine Kritik.<br \/>Ich bin geheilt. Ich habe nun eine Pers\u00f6nlichkeit.<br \/>Ganz sicher hat die Hilfe beim Entschl\u00fcsseln der erhaltenen Botschaften durch Jacotte eine gro\u00dfe Rolle bei dieser Heilung gespielt.<br \/>Dies ist die ganz nat\u00fcrliche Rolle des Therapeuten.<\/p>\n<p>Aber alle wichtigen Informationen sind durch das superlichte Bewusstsein das Adeline selbst erreichte, herbeigebracht worden.<\/p>\n<p>Die psychologischen Effekte der Multidimensionale Musik<br \/>Ein gro\u00dfes Gl\u00fcck f\u00fcr Jacotte war ohne Zweifel, dass sie Wissenschaftlern begegnet ist, die sie vom Wert ihrer Arbeit hat \u00fcberzeugen k\u00f6nnen und, die mit ihr zusammengearbeitet haben. So stellt ihr Professor Dutheil einen ganzen theoretischen Rahmen zur Verf\u00fcgung, ihre Entdeckungen in das allgemeine Panorama der aktuellen Erkenntnisse hinein zu stellen, so bringt die<br \/>Zusammenarbeit mit der Biologin Lydie Ries den sehr konkreten Beweis der Wirkung der Multidimensionale Musik auf den menschlichen K\u00f6rper.<\/p>\n<p>Auch, wenn diese Untersuchungen erst an ihrem Anfang stehen, so haben sie doch bereits sehr \u00fcberzeugende Ergebnisse gebracht.<br \/>Die Biologin hat von Freiwilligen Blutentnahmen vor und nach dem H\u00f6ren genommen.<\/p>\n<p>Man hat deutliche Unterschiede zwischen der Zusammensetzung des Blutes vor und nach dem H\u00f6ren festgestellt:<br \/>Deutliche Abweichungen der Anzahl der wei\u00dfen Blutk\u00f6rperchen, eine wesentliche Erh\u00f6hung des H\u00e4moglobins und schlie\u00dflich<br \/>eine offensichtliche Verlangsamung des Alterns der Zellen.<\/p>\n<p>Zu dieser letzten Feststellung, die Horizonte er\u00f6ffnet, ist man durch einen dieser bekannten kleinen Zuf\u00e4lle gekommen, die so oft die Basis f\u00fcr gro\u00dfe Entdeckungen bilden.<\/p>\n<p>Es war in der Tat so, durch die Untersuchung von Blutproben, die 3 Tage im K\u00fchlschrank vergessen worden waren, sagt Lydie Ries konnte ich mit \u00dcberraschung feststellen, dass die wei\u00dfen Blutk\u00f6rperchen, die ich vor dem H\u00f6ren abgenommen hatte, in einem erb\u00e4rmlichen Zustand waren (ein normales Alterungsph\u00e4nomen angesichts des Zeitraums ), diejenigen, die die Musik geh\u00f6rt hatten, waren sehr viel besser erhalten.<\/p>\n<p>Sie hatten ihre urspr\u00fcngliche Form beibehalten und blieben im Gegensatz zu den anderen weiterhin analysierbar. Dies bedeutete, dass sie im Verlauf der H\u00f6r-Sitzung eine Energie erhalten hatten, die sie weiterhin bei guter Gesundheit bleiben lie\u00df, das hei\u00dft, strukturiert, obwohl sie vom K\u00f6rper und vom Bewusstsein getrennt waren&#8230;<\/p>\n<p>Aus diesen ersten Untersuchungen kann man bereits folgern, dass die MMD einerseits auf die Aktivierung des Zell-Lebens wirkt und andererseits den Alterungsprozesses der Zellen verz\u00f6gert.<\/p>\n<p>Wie aber erkl\u00e4rt sich dies wissenschaftlich?<br \/>Gem\u00e4ss dem deutschen Physiker Popp w\u00e4re die DNA, die grundlegende Struktur der Zelle, eine Art elektromagnetische Antenne.<\/p>\n<p>Es ist also diese Antenne, die die Informationen, die von der Multidimensionale Musik von Jacotte Chollet ausgesandt werden, auff\u00e4ngt und in unsere Zellen \u00fcbertr\u00e4gt.<br \/>Unter rein physiologischen und medizinischen Gesichtspunkten hat der Anstieg des Sauerstoffgehaltes im Blut, herbeigef\u00fchrt durch die Multidimensionale Musik, wohltuende Konsequenzen. All diejenigen, die abgespannt in die Sitzungen der Multidimensionale Musik gegangen sind, best\u00e4tigen, dass sie hinterher ausgeglichener, erholter und energiegeladener waren.<\/p>\n<h5>ZUM H\u00d6REN DER KL\u00c4NGEKANN MAN ES ALLEINE MACHEN UND WIE?<\/h5>\n<p>Ich gebe denen, die bei mir Rat suchen, das Werkzeug, das ihnen erm\u00f6glicht, zu ihrem wahren Sein vorzudringen, zu dem jeder von uns im Laufe seines Lebens den Faden verloren hat, sagt Jacotte Chollet.<\/p>\n<p>Es ist ein Werkzeug zur Vorbeugung, damit sie lernen, die Dinge in die Hand zu nehmen und, dass sie sich selbst heilen k\u00f6nnen.<br \/>Sitzungen mit der MMD zu machen, ist eine Entscheidung die man mit sich selbst trifft.<br \/>Das ist keine intellektuelle Arbeit, jedermann hat Zugang zu diesem Weg.<\/p>\n<p>Das ist der Fall bei Marie Claire B&#8230; 50 Jahre alt, die seit 20 Jahren an st\u00e4ndiger Schlaflosigkeit litt.<\/p>\n<p>Ich war mit Schlafmitteln und mit Vitaminen behandelt worden, erkl\u00e4rt sie.<br \/>Ich hatte keine Tatkraft mehr und keinerlei Kraft, und ich f\u00fchlte mich immer deprimierter. Schlie\u00dflich habe ich von der Multidimensionale Musik geh\u00f6rt.<\/p>\n<p>Ich habe begonnen, indem ich mir die CD gekauft habe, die den Titel RENAISSANCE tr\u00e4gt. Ich habe die Anweisung befolgt, wie ich sie h\u00f6ren soll. So richtig daran geglaubt habe ich zwar nicht, aber ich habe beschlossen, mit gutem Willen daran zu gehen, so konnte ich nicht mehr weitermachen!<\/p>\n<p>Ich habe also angefangen, die Platte \u00fcber mehrere Tage aufmerksam zu h\u00f6ren, und seltsamerweise habe ich eine eindeutige Verbesserung meines Schlafes und eine gr\u00f6\u00dfere Vitalit\u00e4t festgestellt.<br \/>Und dann, eines Tages, im Laufe eines H\u00f6rens hatte ich einen pl\u00f6tzlichen Kontakt mit meiner verstorbenen Gro\u00dfmutter. Dies hat mich dazu gebracht, die Arbeit weiterzuverfolgen, und bei Jacotte nach Sitzungen in ihrem Labor nachzufragen.<\/p>\n<p>J\u00e9r\u00f4me Bourgine<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Press artikel EINE MUSIK, DIE IHRE SCHWINGUNGEN Z\u00c4HMT, HARMONISIERT, IHRE ZELLEN REGENERIERT, GESUNDEN WIRD ZU EINER REALIT\u00c4T. Eine erstaunliche Frau, mit ausdrucksstarkem Gesicht, mit Kopf und Herz dabei, dem Gegen\u00fcber zuzuh\u00f6ren:Jacotte Chollet. Regisseurin von Fernsehreportagen.Jahrelang hat sie den Planeten an der Seite ihres Ehemann`s Andre Voisin durchquert, um anderen die spirituellen Traditionen der ganzen Welt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2945","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eine Revolution, gesund werden durch T\u00f6ne - Die Multidimensionale Musik von Jacotte Chollet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine Revolution, gesund werden durch T\u00f6ne\" \/>\n<meta property=\"og:description\" content=\"Press artikel EINE MUSIK, DIE IHRE SCHWINGUNGEN Z\u00c4HMT, HARMONISIERT, IHRE ZELLEN REGENERIERT, GESUNDEN WIRD ZU EINER REALIT\u00c4T. Eine erstaunliche Frau, mit ausdrucksstarkem Gesicht, mit Kopf und Herz dabei, dem Gegen\u00fcber zuzuh\u00f6ren:Jacotte Chollet. Regisseurin von Fernsehreportagen.Jahrelang hat sie den Planeten an der Seite ihres Ehemann`s Andre Voisin durchquert, um anderen die spirituellen Traditionen der ganzen Welt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Multidimensionale Musik von Jacotte Chollet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-16T14:12:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/eine-revolution-gesund-werden-durch-tone\\\/\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/eine-revolution-gesund-werden-durch-tone\\\/\",\"name\":\"Eine Revolution, gesund werden durch T\u00f6ne - Die Multidimensionale Musik von Jacotte Chollet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#website\"},\"datePublished\":\"2017-11-28T10:48:53+00:00\",\"dateModified\":\"2020-01-16T14:12:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/eine-revolution-gesund-werden-durch-tone\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/eine-revolution-gesund-werden-durch-tone\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/eine-revolution-gesund-werden-durch-tone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine Revolution, gesund werden durch T\u00f6ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\",\"name\":\"Jacotte Chollet - La Musique Multidimensionnelle\",\"description\":\"Musik f\u00fcr : Bewusstseinserweiterung - Kreativit\u00e4t - Tiefenentspannung - Massage - Meditation - Selbsthypnose - Stressbek\u00e4mpfung\",\"publisher\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#organization\",\"name\":\"Jacotte Chollet Multidimensional Music\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png\",\"contentUrl\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png\",\"width\":800,\"height\":358,\"caption\":\"Jacotte Chollet Multidimensional Music\"},\"image\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jacottecholletmusiquemultidimensionnelle\\\/\",\"https:\\\/\\\/www.instagram.com\\\/jacottechollet\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jacotte-chollet-41a09812\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKDtAKgspnDQqggI1bAOl_g\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eine Revolution, gesund werden durch T\u00f6ne - Die Multidimensionale Musik von Jacotte Chollet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/","og_locale":"de_DE","og_type":"article","og_title":"Eine Revolution, gesund werden durch T\u00f6ne","og_description":"Press artikel EINE MUSIK, DIE IHRE SCHWINGUNGEN Z\u00c4HMT, HARMONISIERT, IHRE ZELLEN REGENERIERT, GESUNDEN WIRD ZU EINER REALIT\u00c4T. Eine erstaunliche Frau, mit ausdrucksstarkem Gesicht, mit Kopf und Herz dabei, dem Gegen\u00fcber zuzuh\u00f6ren:Jacotte Chollet. Regisseurin von Fernsehreportagen.Jahrelang hat sie den Planeten an der Seite ihres Ehemann`s Andre Voisin durchquert, um anderen die spirituellen Traditionen der ganzen Welt [&hellip;]","og_url":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/","og_site_name":"Die Multidimensionale Musik von Jacotte Chollet","article_publisher":"https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/","article_modified_time":"2020-01-16T14:12:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/","url":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/","name":"Eine Revolution, gesund werden durch T\u00f6ne - Die Multidimensionale Musik von Jacotte Chollet","isPartOf":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#website"},"datePublished":"2017-11-28T10:48:53+00:00","dateModified":"2020-01-16T14:12:12+00:00","breadcrumb":{"@id":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/multidimensionalmusic.com\/de\/eine-revolution-gesund-werden-durch-tone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multidimensionalmusic.com\/de\/"},{"@type":"ListItem","position":2,"name":"Eine Revolution, gesund werden durch T\u00f6ne"}]},{"@type":"WebSite","@id":"https:\/\/multidimensionalmusic.com\/de\/#website","url":"https:\/\/multidimensionalmusic.com\/de\/","name":"Jacotte Chollet - La Musique Multidimensionnelle","description":"Musik f\u00fcr : Bewusstseinserweiterung - Kreativit\u00e4t - Tiefenentspannung - Massage - Meditation - Selbsthypnose - Stressbek\u00e4mpfung","publisher":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multidimensionalmusic.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/multidimensionalmusic.com\/de\/#organization","name":"Jacotte Chollet Multidimensional Music","url":"https:\/\/multidimensionalmusic.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/multidimensionalmusic.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2025\/03\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png","contentUrl":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2025\/03\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png","width":800,"height":358,"caption":"Jacotte Chollet Multidimensional Music"},"image":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/","https:\/\/www.instagram.com\/jacottechollet\/","https:\/\/www.linkedin.com\/in\/jacotte-chollet-41a09812\/","https:\/\/www.youtube.com\/channel\/UCKDtAKgspnDQqggI1bAOl_g"]}]}},"_links":{"self":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages\/2945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/comments?post=2945"}],"version-history":[{"count":0,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages\/2945\/revisions"}],"wp:attachment":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/media?parent=2945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}