{"id":2819,"date":"2017-11-27T14:42:36","date_gmt":"2017-11-27T13:42:36","guid":{"rendered":"https:\/\/multidimensionalmusic.com\/?page_id=2819"},"modified":"2025-06-24T14:57:54","modified_gmt":"2025-06-24T12:57:54","slug":"wirkung-von-multidimensionale-musik-auf-blutzellen","status":"publish","type":"page","link":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/","title":{"rendered":"Wirkung von Multidimensionale Musik auf blutzellen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2819\" class=\"elementor elementor-2819 elementor-21\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ce6afb9 e-flex e-con-boxed e-con e-parent\" data-id=\"2ce6afb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d66a1b elementor-widget elementor-widget-heading\" data-id=\"6d66a1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diese Musik stimuliert die Eigenresonanz auf zellul\u00e4rer Ebene.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7713532 elementor-widget elementor-widget-text-editor\" data-id=\"7713532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>W\u00e4hrend der Bewusstseins-Erweiterungsseminare, die zwischen 1992 und 1994 (in Zusammenarbeit mit Professor R\u00e9gis Dutheil) organisiert wurden, entwickelte sich eine Studie \u00fcber die spezifischen Wirkungen der Multidimensionalen Musik von Jacotte Chollet auf Psyche und K\u00f6rper.<\/strong><\/p><p>Diese Forschung zeigt, dass unsere Zellen Musik h\u00f6ren, dass sie schwingen, dass sie in Resonanz gehen und dass es eine unmittelbare Wechselwirkung zwischen unseren Bewusstseinszust\u00e4nden, dem Energiefluss und der Chemie unserer Zellen gibt.<\/p><p>Bei freiwilligen Teilnehmern wurden Blutproben VOR und NACH EINER STUNDE TIEFEN H\u00d6RENS dieser Musik entnommen.<\/p><p><strong>Die Analyse der Blutproben ergab, dass eine Erh\u00f6hung des Schwingungsniveaus und eine Ausdehnung des Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67bb74e elementor-widget elementor-widget-text-editor\" data-id=\"67bb74e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bereits nach nur einer Stunde H\u00f6ren dieser Musik wurde festgestellt:<\/strong><\/p><p><strong>\u2013 EINE ZUNAHME DER ANZAHL DER ROTEN BLUTK\u00d6RPERCHEN<\/strong><br \/><strong>\u2013 EINE HYPEROXYGENIERUNG DES BLUTES<\/strong><br \/><strong>\u2013 EINE ZUNAHME DER ANZAHL DER WEISSEN BLUTK\u00d6RPERCHEN<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f3f2b elementor-widget elementor-widget-text-editor\" data-id=\"07f3f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Die Ausdehnung des Bewusstseinsfeldes, die energetische Vereinigung und Harmonisierung, die w\u00e4hrend des H\u00f6rens dieser Musik stattfanden, f\u00fchrten zu einem h\u00f6heren Ma\u00df an zellul\u00e4rer Organisation, das der zerst\u00f6rerischen Wirkung der Entropie besser widersteht.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc9275c elementor-widget elementor-widget-heading\" data-id=\"fc9275c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ANALYSES EN LABORATOIRE SUR LA CELLULE SANGUINE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daceb82 elementor-widget elementor-widget-text-editor\" data-id=\"daceb82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Studie wurde an Blutproben durchgef\u00fchrt, die <em>vor<\/em> und <em>nach<\/em> dem Anh\u00f6ren der Musik von Jacotte Chollet w\u00e4hrend therapeutischer Sitzungen und Seminare (H\u00f6rdauer 1 bis 1,5 Stunden) entnommen wurden.<\/p><p>\u00a0<\/p><p><strong>Es wurde festgestellt:<\/strong><\/p><ul><li><strong>Eine deutliche Erh\u00f6hung des H\u00e4moglobin<\/strong>&#8211; und Oxyh\u00e4moglobinspiegels, mit bis zu +2g\/l nach 1,5 Stunden Anh\u00f6ren.<\/li><li><strong>Eine sp\u00fcrbare Zunahme der Anzahl der wei\u00dfen Blutk\u00f6rperchen.<\/strong><\/li><li><strong>Eine positive Wirkung auf die Zellalterung:<\/strong> eine Zunahme der neutrophilen Granulozyten um bis zu 4700\/mm\u00b3, was auf eine intensive innere \u201eReinigungsarbeit\u201c hindeutet.<\/li><\/ul><p>Bei der Entnahme der Blutproben konnte mit blo\u00dfem Auge eine Reinigung und Hyperoxygenierung des Blutes festgestellt werden: Das Blut war <em>vor dem Anh\u00f6ren<\/em> dunkelrot (Farbe des ven\u00f6sen, mit Toxinen belasteten Blutes) und wurde <em>nach dem Anh\u00f6ren<\/em> leuchtend rot (gewaschen, mit Sauerstoff angereichert).<\/p><p><strong>Eines Tages wurden w\u00e4hrend eines Seminars entnommene Blutproben im K\u00fchlschrank vergessen und erst drei Tage sp\u00e4ter analysiert.<\/strong><\/p><p><strong>Dieses unbeabsichtigte Versehen erm\u00f6glichte es, die negentropische Wirkung der Multidimensionalen Musik auf die Blutzelle objektiv zu beobachten.<br \/><\/strong><em><strong>Negentropie ist eine Zunahme von Ordnung und Energie, die den zerst\u00f6rerischen Effekten der Entropie entgegenwirkt.<\/strong><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26fedef elementor-widget elementor-widget-heading\" data-id=\"26fedef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PROBEN VOR UND NACH DEM ANH\u00d6REN<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e19d770 e-flex e-con-boxed e-con e-parent\" data-id=\"e19d770\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8a9665e e-con-full e-flex e-con e-child\" data-id=\"8a9665e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5bd9f75 e-con-full e-flex e-con e-child\" data-id=\"5bd9f75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fcbcb5 elementor-widget elementor-widget-image\" data-id=\"7fcbcb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"132\" height=\"128\" src=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg\" class=\"attachment-full size-full wp-image-567\" alt=\"wirkung von musik jacotte chollet auf blutzellen\" srcset=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg 132w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1-50x48.jpg 50w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1-77x75.jpg 77w\" sizes=\"(max-width: 132px) 100vw, 132px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3024422 elementor-widget elementor-widget-text-editor\" data-id=\"3024422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Kontrollprobe:<\/strong><br \/>Frische Blutzelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ae0180 e-con-full e-flex e-con e-child\" data-id=\"4ae0180\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51692a5 elementor-widget elementor-widget-image\" data-id=\"51692a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"130\" height=\"131\" src=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2.jpg\" class=\"attachment-full size-full wp-image-562\" alt=\"BLUTZELLEN NACH 3 TAGEN vor dem H\u00f6ren der Multidimensionale Musik\" srcset=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2.jpg 130w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2-50x50.jpg 50w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2-74x75.jpg 74w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2-85x85.jpg 85w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule2-80x80.jpg 80w\" sizes=\"(max-width: 130px) 100vw, 130px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08b0422 elementor-widget elementor-widget-text-editor\" data-id=\"08b0422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Probe VOR dem Anh\u00f6ren<\/strong><br \/>der Multidimensionalen Musik,<br \/><strong>3 Tage sp\u00e4ter analysiert.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97829b9 e-con-full e-flex e-con e-child\" data-id=\"97829b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc63264 elementor-widget elementor-widget-image\" data-id=\"bc63264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"132\" height=\"128\" src=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule3.jpg\" class=\"attachment-full size-full wp-image-557\" alt=\"BLUTZELLEN NACH 3 TAGEN, nach dem H\u00f6ren der Multidimensionale Musik.\" srcset=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule3.jpg 132w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule3-50x48.jpg 50w, https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule3-77x75.jpg 77w\" sizes=\"(max-width: 132px) 100vw, 132px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-578b22f elementor-widget elementor-widget-text-editor\" data-id=\"578b22f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Probe NACH 1 Stunde Anh\u00f6ren<\/strong><br \/>beim selben Probanden,<br \/><strong>3 Tage sp\u00e4ter analysiert.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-456e201 e-flex e-con-boxed e-con e-parent\" data-id=\"456e201\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c3490e e-con-full e-flex e-con e-child\" data-id=\"7c3490e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-eeee157 e-con-full e-flex e-con e-child\" data-id=\"eeee157\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6af6cc elementor-widget elementor-widget-heading\" data-id=\"f6af6cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FOLIE 1: KONTROLLPROBE<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d22cc0 elementor-widget elementor-widget-text-editor\" data-id=\"1d22cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"kc-elm kc-css-2163622 kc_text_block\"><p>Frische Blutzelle.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ba715c elementor-widget elementor-widget-heading\" data-id=\"0ba715c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FOLIE 2: PROBE VOR DEM ANH\u00d6REN, 3 TAGE SP\u00c4TER ANALYSIERT<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed2f6bf elementor-widget elementor-widget-text-editor\" data-id=\"ed2f6bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"kc-elm kc-css-2163622 kc_text_block\"><p><strong>Man stellt das Platzen des Zellkerns fest, seine Form und Information sind verschwunden.<\/strong><br \/><strong>Die Wirkung der Zeit (ENTROPIE) hat Unordnung und zellul\u00e4re Alterung verursacht.<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b644b9 elementor-widget elementor-widget-heading\" data-id=\"2b644b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FOLIE 3: PROBE NACH 1 STUNDE ANH\u00d6REN, 3 TAGE SP\u00c4TER ANALYSIERT<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-778ce56 elementor-widget elementor-widget-text-editor\" data-id=\"778ce56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"kc-elm kc-css-2163622 kc_text_block\"><p><strong>Der Zellkern wurde trotz 3 Tagen Alterung zu 75 % erhalten.<\/strong><br \/><strong>Die NEG-ENTROPISCHE Wirkung der MULTIDIMENSIONALEN Musik hat die Information und Organisation der Zelle bewahrt.<\/strong><\/p><p><strong>\u00a0<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-054b98b elementor-widget elementor-widget-text-editor\" data-id=\"054b98b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Bewusstseinserweiterung und energetische Harmonisierung, die durch diese Musik hervorgerufen werden, haben <strong>eine Zunahme der Negentropie (Ordnung) auf zellul\u00e4rer<\/strong> <strong>Ebene und eine Verringerung des entropischen Effekts (Unordnung, Alterung) durch die Zeit erm\u00f6glicht.<\/strong>*<\/p><p><strong>Im Gegensatz zur Entropie, die eine Zunahme von Unordnung im Universum ausdr\u00fcckt, ist Negentropie eine Durchdringung von Ordnung und Koh\u00e4renz in der Struktur der Materie. Anders gesagt, Negentropie ist eine Informationskraft, die die Strukturen und Funktionen lebender Systeme organisiert und an der interzellul\u00e4ren Biokommunikation beteiligt ist.<\/strong><\/p><p><em>*Analysen wurden nach 3 Tagen durchgef\u00fchrt.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6b3e52 elementor-widget elementor-widget-heading\" data-id=\"e6b3e52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">VORTEILE DER \u00dcBERS\u00c4TTIGUNG DES BLUTES MIT SAUERSTOFF<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82f1dec elementor-widget elementor-widget-text-editor\" data-id=\"82f1dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>(Erh\u00f6hung des Anteils an sauerstoffges\u00e4ttigtem H\u00e4moglobin)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96edfbe elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"96edfbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h4 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Auf zerebraler Ebene<\/span>\n\t\t\t\t\t\t\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"uael-subheading elementor-inline-editing\" data-elementor-setting-key=\"heading_description\" data-elementor-inline-editing-toolbar=\"advanced\" >\n\t\t\t\t\tStimulation und Regulierung der Gehirnfunktionen:\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92b73d elementor-widget elementor-widget-text-editor\" data-id=\"f92b73d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ged\u00e4chtnisbildung, Ideenfindung, antidepressive Wirkung, Verz\u00f6gerung der Alterung und Unterst\u00fctzung bei zerebrovaskul\u00e4ren Behandlungen.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb587c elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"8bb587c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h4 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">IMMUN- UND H\u00c4MATOPOETISCHES SYSTEM durch Stimulation der Blutzelllinie.<\/span>\n\t\t\t\t\t\t\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"uael-subheading elementor-inline-editing\" data-elementor-setting-key=\"heading_description\" data-elementor-inline-editing-toolbar=\"advanced\" >\n\t\t\t\t\tDas Anh\u00f6ren dieser Musik, selbst als Hintergrundmusik, stimuliert und unterst\u00fctzt das Immunsystem. Ihr Anh\u00f6ren wird daher besonders w\u00e4hrend der Rekonvaleszenz oder in epidemischen Phasen empfohlen.\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd5c6b elementor-widget elementor-widget-text-editor\" data-id=\"2fd5c6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>W\u00e4hrend Chemotherapiesitzungen hat das gleichzeitige Anh\u00f6ren des Albums <a href=\"https:\/\/jacottechollet.com\/de\/products\/renaissance\" target=\"_blank\" rel=\"noopener\">RENAISSANCE<\/a> erwiesen, dass es eine wirksame Hilfe ist, um deren zerst\u00f6rerische Nebenwirkungen auf das Blutbild entgegenzuwirken.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad32ca1 elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"ad32ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h4 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Wirkung auf das NERVENSYSTEM<\/span>\n\t\t\t\t\t\t\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"uael-subheading elementor-inline-editing\" data-elementor-setting-key=\"heading_description\" data-elementor-inline-editing-toolbar=\"advanced\" >\n\t\t\t\t\tAnti-Stress-Wirkung, f\u00f6rdert die Konzentration, beruhigt Kinder und hyperaktive Personen.\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fc23a1 elementor-widget elementor-widget-text-editor\" data-id=\"8fc23a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>W\u00e4hrend des Lernens oder in Pr\u00fcfungsphasen f\u00f6rdert das Anh\u00f6ren dieser Musik bei mittlerer oder niedriger Lautst\u00e4rke die Merkf\u00e4higkeit, erm\u00f6glicht es, ohne Anstrengung konzentriert zu bleiben und einen klaren Geist zu bewahren.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd19c7 elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"1fd19c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h4 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Wirkung auf den STOFFWECHSEL &amp; das MUSKUL\u00c4RE POTENZIAL<\/span>\n\t\t\t\t\t\t\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"uael-subheading elementor-inline-editing\" data-elementor-setting-key=\"heading_description\" data-elementor-inline-editing-toolbar=\"advanced\" >\n\t\t\t\t\tSauerstoff bewirkt eine Erh\u00f6hung des Grund- und Zellstoffwechsels, eine Ausscheidung von Fetten und Abfallstoffen aus dem K\u00f6rper mit R\u00fcckwirkung auf bestimmte endokrine Dr\u00fcsen wie Schilddr\u00fcse, Hypophyse und Nebennieren, sowie eine Beschleunigung der Wundheilung.\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0058ca elementor-widget elementor-widget-text-editor\" data-id=\"c0058ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bessere Ausscheidung der bei der Muskelverbrennung entstehenden Abfallstoffe, erleichterte Erholung nach Anstrengung (Sportler).<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caff76c elementor-widget elementor-widget-text-editor\" data-id=\"caff76c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Unsere Emotionen beeinflussen st\u00e4ndig unsere K\u00f6rperchemie.<\/strong><\/h3><p>Unsere Erwartungen, unsere Perspektiven, wahre Verbindung mit unserem tiefen Selbst sind Parameters, die unsere K\u00f6rperfunktionen stark beeinflussen.<br \/>Es ist bewiesen, da\u00df negative Emotionen zerst\u00f6rerisch f\u00fcr unseren K\u00f6rper sind. (<a href=\"https:\/\/www.semel.ucla.edu\/initiatives\/cousins\/\" target=\"_blank\" rel=\"noopener\">Norman COUSINS<\/a> U.C.L.A.)<\/p><p class=\"my-0\"><strong>Indem sie h\u00f6here Bewusstseinszust\u00e4nde hervorruft, die sich durch tiefe Selbstwertsch\u00e4tzung und Freude \u00e4u\u00dfern, erzeugt die Musik von Jacotte Chollet eine neue \u201eChemie\u201c, die mit dem physischen K\u00f6rper interagiert.<br \/><\/strong><strong>Das Ergebnis ist mehr Vitalit\u00e4t, mehr Energie, gesteigerte Leistungsf\u00e4higkeit sowie mehr Lebensfreude und Kreativit\u00e4t.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8a83c9 elementor-widget elementor-widget-text-editor\" data-id=\"e8a83c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>In verschiedenen L\u00e4ndern wird die Multidimensionale Musik von Therapeuten, Psychiatern, Psychologen, Logop\u00e4den, Lehrern, Energiearbeitern, Entspannungstherapeuten, Sophrologen, Osteopathen und \u00c4rzten eingesetzt. Sie hat sich als ein schwingungsbasiertes Werkzeug erwiesen, das ihre eigene therapeutische Praxis optimiert und wirksamer macht.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42a798 elementor-widget elementor-widget-text-editor\" data-id=\"e42a798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"my-0\"><strong>ANSTIEG DES H\u00c4MOGLOBINSPIEGELS W\u00c4HREND DER CHEMOTHERAPIE<\/strong><\/h3><p class=\"my-0\"><em>Ich habe an Ihrer Pr\u00e4sentation im Zentrum f\u00fcr Integrative Medizin in San Jos\u00e9 teilgenommen, Ihre Alben gekauft und mit dem Anh\u00f6ren begonnen.<\/em><br \/><em>Mein H\u00e4moglobinwert ist innerhalb von zwei Wochen von 12,00 auf 13,2 gestiegen, obwohl ich Herceptin einnehme, ein Krebsmedikament, das normalerweise den H\u00e4moglobinspiegel senkt.<\/em><br \/><em>Bei meiner letzten Analyse war die Gesamtzahl meiner wei\u00dfen Blutk\u00f6rperchen erheblich gestiegen, von 5,1 auf 9,6.<\/em><\/p><p class=\"my-0\"><em>Ich habe <strong><a href=\"https:\/\/jacottechollet.com\/de\/products\/sky-dancing\" target=\"_blank\" rel=\"noopener\">SKY DANCING<\/a><\/strong> mehrmals pro Woche geh\u00f6rt. Beim ersten Mal habe ich eine intensive K\u00e4lte empfunden.<\/em><\/p><p class=\"my-0\"><em>Diese ausgezeichneten Ergebnisse freuen mich sehr, ich habe meinen Emotionalk\u00f6rper weiterentwickelt und bin Ihnen sehr dankbar.<\/em><br \/><em>Bei meiner letzten Analyse hatte ich einen H\u00e4moglobinwert von 14,0.<\/em><br \/><em>Ich bin fasziniert von der Wirkung Ihrer Musik auf mich und danke Ihnen herzlich.<\/em><\/p><p>JEAN SEAMAN<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7465fcf elementor-widget elementor-widget-text-editor\" data-id=\"7465fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"my-0\"><strong>BEGLEITUNG BEI DER CHEMOTHERAPIE<\/strong><\/h3><p class=\"my-0\"><em>Hallo Jacotte,<\/em><br \/><em>Ich habe Sie an Ihrem Stand auf der Messe \u201eM\u00e9decines Douces\u201c in Paris getroffen, um von den Vorteilen zu berichten, die ich durch das Anh\u00f6ren Ihres Albums <strong><a href=\"https:\/\/jacottechollet.com\/de\/products\/renaissance\" target=\"_blank\" rel=\"noopener\">RENAISSANCE<\/a><\/strong> erfahren habe.<\/em><\/p><p class=\"my-0\"><em>Ich habe n\u00e4mlich Brustkrebs und folge einem Behandlungsprotokoll am Curie-Institut.<\/em><br \/><em>Ich habe das Ende dieser Behandlungen abgewartet, um Ihnen mein ganz einfaches, aber sehr dankbares Zeugnis zu schicken.<\/em><\/p><p class=\"my-0\"><em>Ich habe 8 Chemotherapiesitzungen durchlaufen, davon 4 mit einem Medikament namens Taxotere, das einen k\u00f6rperlich zerst\u00f6rt (\u00dcbelkeit, Magenbrennen, Verlust von N\u00e4geln und Haaren und vor allem sehr starke Gelenkschmerzen).<\/em><\/p><p class=\"my-0\"><em>Ab der zweiten Chemotherapiesitzung habe ich Ihr Album <strong><a href=\"https:\/\/jacottechollet.com\/de\/products\/renaissance\" target=\"_blank\" rel=\"noopener\">RENAISSANCE<\/a><\/strong> geh\u00f6rt.<\/em><br \/><em>Warum ab der zweiten Sitzung?<\/em><br \/><em>Vor jeder Sitzung wird eine Blutuntersuchung gemacht. Die, die meiner ersten Chemotherapie vorausging, zeigte einen R\u00fcckgang der roten Blutk\u00f6rperchen in meinem Blutbild.<\/em><\/p><p class=\"my-0\"><em>Auf Anraten meines Kollegen Louis habe ich Ihre Musik geh\u00f6rt; ich muss zugeben, dass ich diesen musikalischen Moment anfangs eher als eine M\u00f6glichkeit sah, um mich zu entspannen, um mir zu helfen, die Umgebung und das Unwohlsein zu ertragen.<\/em><\/p><p class=\"my-0\"><em>Aber ich muss zu meiner gro\u00dfen \u00dcberraschung anerkennen, dass alle meine Blutwerte im Normbereich geblieben sind und es mir erm\u00f6glicht haben, die gesamte Behandlung ohne Unterbrechung zu absolvieren \u2013 im Gegensatz zu den Personen, die gleichzeitig mit mir begonnen hatten.<\/em><\/p><p class=\"my-0\"><em>Anschlie\u00dfend wurde ich operiert und habe 25 Sitzungen Strahlentherapie erhalten. Ich habe es geschafft, diese sowohl k\u00f6rperlich als auch psychisch schmerzhafte Zeit dank meines Umfelds und dank Ihrer Musik, insbesondere durch das Anh\u00f6ren von <strong><a href=\"https:\/\/jacottechollet.com\/de\/products\/renaissance\" target=\"_blank\" rel=\"noopener\">RENAISSANCE<\/a><\/strong>, zu \u00fcberstehen.<\/em><\/p><p class=\"my-0\"><em>Ich besitze noch weitere Alben Ihrer Multidimensionalen Musik, aber RENAISSANCE hat mir am meisten geholfen, mich zu regenerieren.<\/em><\/p><p class=\"my-0\"><em>W\u00e4hrend meiner Behandlung im Curie-Institut konnte ich anderen Patienten, die an derselben Krankheit litten und neugierig auf meine t\u00e4gliche Energie waren, von der Wirksamkeit Ihrer Musik berichten.<\/em><br \/><em>Ich bin Ihnen daher sehr dankbar, dass Sie einer der wirksamen Faktoren sind, die mir helfen, diesen Krebs zu besiegen.<\/em><\/p><p class=\"my-0\"><strong><em>Das Anh\u00f6ren von <a href=\"https:\/\/jacottechollet.com\/de\/products\/renaissance\" target=\"_blank\" rel=\"noopener\">RENAISSANCE<\/a> fand w\u00e4hrend und nach der Chemotherapie statt.<\/em><\/strong><\/p><p><strong>MARYSE<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af41be7 elementor-widget elementor-widget-text-editor\" data-id=\"af41be7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"my-0\"><em>Ich bin erstaunt zu sehen, dass diese Jugendlichen, die sich normalerweise nur schwer auf eine Aufgabe konzentrieren k\u00f6nnen, eine Stunde lang still und ohne M\u00fche arbeiten, w\u00e4hrend sie die Multidimensionale Musik h\u00f6ren!<\/em><br \/><em>Die Sch\u00fcler rufen sich nicht mehr laut zu, sie sprechen ganz nat\u00fcrlich leiser.<\/em><br \/><em>Ein Gespr\u00e4ch kann in gegenseitigem Respekt entstehen.<\/em><\/p><p class=\"my-0\"><strong>CATHERINE \u2013 Lehrerin an einem spezialisierten Institut.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-351119d elementor-widget elementor-widget-text-editor\" data-id=\"351119d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><a href=\"https:\/\/multidimensionalmusic.com\/de\/erfahrungen-von-therapeuten-musik-jacotte-chollet\/\">ANDEREN ERFAHRUNGEN THERAPEUTEN<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45106db elementor-widget elementor-widget-text-editor\" data-id=\"45106db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Die eigentliche Bestimmung dieser Musik ist es, ein pers\u00f6nliches Werkzeug f\u00fcr Erwachen, Selbstst\u00e4ndigkeit, energetische Selbstregulation, Selbstf\u00fcrsorge sowie f\u00fcr die Vervielfachung der kreativen F\u00e4higkeiten und des verborgenen Potenzials des eigenen Seins zu sein, wie zahlreiche H\u00f6rer bezeugen<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcced5f e-flex e-con-boxed e-con e-parent\" data-id=\"fcced5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4c902a elementor-widget elementor-widget-spacer\" data-id=\"f4c902a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Diese Musik stimuliert die Eigenresonanz auf zellul\u00e4rer Ebene. W\u00e4hrend der Bewusstseins-Erweiterungsseminare, die zwischen 1992 und 1994 (in Zusammenarbeit mit Professor R\u00e9gis Dutheil) organisiert wurden, entwickelte sich eine Studie \u00fcber die spezifischen Wirkungen der Multidimensionalen Musik von Jacotte Chollet auf Psyche und K\u00f6rper. Diese Forschung zeigt, dass unsere Zellen Musik h\u00f6ren, dass sie schwingen, dass sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2819","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wirkung von Multidimensionale Musik auf blutzellen - Die Multidimensionale Musik von Jacotte Chollet<\/title>\n<meta name=\"description\" content=\"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wirkung von Multidimensionale Musik auf blutzellen\" \/>\n<meta property=\"og:description\" content=\"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Multidimensionale Musik von Jacotte Chollet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T12:57:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/\",\"name\":\"Wirkung von Multidimensionale Musik auf blutzellen - Die Multidimensionale Musik von Jacotte Chollet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/recherche-musique-jacotte-cellule1.jpg\",\"datePublished\":\"2017-11-27T13:42:36+00:00\",\"dateModified\":\"2025-06-24T12:57:54+00:00\",\"description\":\"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/recherche-musique-jacotte-cellule1.jpg\",\"contentUrl\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/recherche-musique-jacotte-cellule1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/wirkung-von-multidimensionale-musik-auf-blutzellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wirkung von Multidimensionale Musik auf blutzellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\",\"name\":\"Jacotte Chollet - La Musique Multidimensionnelle\",\"description\":\"Musik f\u00fcr : Bewusstseinserweiterung - Kreativit\u00e4t - Tiefenentspannung - Massage - Meditation - Selbsthypnose - Stressbek\u00e4mpfung\",\"publisher\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#organization\",\"name\":\"Jacotte Chollet Multidimensional Music\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png\",\"contentUrl\":\"https:\\\/\\\/multidimensionalmusic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png\",\"width\":800,\"height\":358,\"caption\":\"Jacotte Chollet Multidimensional Music\"},\"image\":{\"@id\":\"https:\\\/\\\/multidimensionalmusic.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jacottecholletmusiquemultidimensionnelle\\\/\",\"https:\\\/\\\/www.instagram.com\\\/jacottechollet\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jacotte-chollet-41a09812\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKDtAKgspnDQqggI1bAOl_g\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wirkung von Multidimensionale Musik auf blutzellen - Die Multidimensionale Musik von Jacotte Chollet","description":"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/","og_locale":"de_DE","og_type":"article","og_title":"Wirkung von Multidimensionale Musik auf blutzellen","og_description":"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.","og_url":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/","og_site_name":"Die Multidimensionale Musik von Jacotte Chollet","article_publisher":"https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/","article_modified_time":"2025-06-24T12:57:54+00:00","og_image":[{"url":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/","url":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/","name":"Wirkung von Multidimensionale Musik auf blutzellen - Die Multidimensionale Musik von Jacotte Chollet","isPartOf":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/#primaryimage"},"image":{"@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/#primaryimage"},"thumbnailUrl":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg","datePublished":"2017-11-27T13:42:36+00:00","dateModified":"2025-06-24T12:57:54+00:00","description":"Bewusstseinsfeldes der Zuh\u00f6rer, ausgel\u00f6st durch das H\u00f6ren dieser Musik, eine Transformation auf der Ebene der Blutzellen bewirken.","breadcrumb":{"@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/#primaryimage","url":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg","contentUrl":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2017\/07\/recherche-musique-jacotte-cellule1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/multidimensionalmusic.com\/de\/wirkung-von-multidimensionale-musik-auf-blutzellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multidimensionalmusic.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wirkung von Multidimensionale Musik auf blutzellen"}]},{"@type":"WebSite","@id":"https:\/\/multidimensionalmusic.com\/de\/#website","url":"https:\/\/multidimensionalmusic.com\/de\/","name":"Jacotte Chollet - La Musique Multidimensionnelle","description":"Musik f\u00fcr : Bewusstseinserweiterung - Kreativit\u00e4t - Tiefenentspannung - Massage - Meditation - Selbsthypnose - Stressbek\u00e4mpfung","publisher":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multidimensionalmusic.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/multidimensionalmusic.com\/de\/#organization","name":"Jacotte Chollet Multidimensional Music","url":"https:\/\/multidimensionalmusic.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/multidimensionalmusic.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2025\/03\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png","contentUrl":"https:\/\/multidimensionalmusic.com\/wp-content\/uploads\/2025\/03\/header-logo-site-vitrine-jacotte-chollet-mmd-transparent.png","width":800,"height":358,"caption":"Jacotte Chollet Multidimensional Music"},"image":{"@id":"https:\/\/multidimensionalmusic.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jacottecholletmusiquemultidimensionnelle\/","https:\/\/www.instagram.com\/jacottechollet\/","https:\/\/www.linkedin.com\/in\/jacotte-chollet-41a09812\/","https:\/\/www.youtube.com\/channel\/UCKDtAKgspnDQqggI1bAOl_g"]}]}},"_links":{"self":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages\/2819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/comments?post=2819"}],"version-history":[{"count":67,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages\/2819\/revisions"}],"predecessor-version":[{"id":91475,"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/pages\/2819\/revisions\/91475"}],"wp:attachment":[{"href":"https:\/\/multidimensionalmusic.com\/de\/wp-json\/wp\/v2\/media?parent=2819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}